{"id":96,"date":"2026-06-03T11:05:17","date_gmt":"2026-06-03T11:05:17","guid":{"rendered":"https:\/\/wp-estates.com\/?page_id=96"},"modified":"2026-07-01T19:23:20","modified_gmt":"2026-07-01T19:23:20","slug":"ueber-uns","status":"publish","type":"page","link":"https:\/\/wp-estates.com\/en\/ueber-uns\/","title":{"rendered":"About"},"content":{"rendered":"\n<p class=\"has-text-align-center has-text-color has-link-color wp-elements-2060be29b03f4e085419d0583a1c030d wp-block-paragraph\" style=\"color:#c4a35a\">Unternehmerisch. Diskret. Pers\u00f6nlich<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-154adf5cbf34376d1e7b43f3f37b33ea\" style=\"color:#9a9a9a\">\u00dcber W&amp;P Estates<\/h2>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-f781bc826bad7976ffa493451675a376 wp-block-paragraph\" style=\"color:#9a9a9a\">Unternehmerische Erfahrung. Internationale Perspektive. Pers\u00f6nliche Beratung.<\/p>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-c2b611f559ff0728a860ed5be50cdcf3 wp-block-paragraph\" style=\"color:#9a9a9a\">W&amp;P Estates ist eine inhabergef\u00fchrte Boutique-Beratung f\u00fcr Off-Market-Immobilien, Investmenttransaktionen und strategische Immobilienberatung. Seit mehr als 25 Jahren begleiten wir Eigent\u00fcmer, Unternehmerfamilien, Investoren und Projektentwickler bei anspruchsvollen Immobilienvorhaben \u2013 diskret, pers\u00f6nlich und mit unternehmerischem Verst\u00e4ndnis.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-375a11b1a99b964d8664d58d8fa9ff61\" style=\"color:#9a9a9a\">Unsere Philosophie<\/h2>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-ec8c226f08a0d201d65789a622139a3c wp-block-paragraph\" style=\"color:#9a9a9a\">Immobilien sind mehr als Verm\u00f6genswerte \u2013 sie sind unternehmerische Entscheidungen, langfristige Investitionen und h\u00e4ufig Teil einer Familiengeschichte. Deshalb begleiten wir jede Transaktion mit dem gleichen Anspruch, den wir auch an eigene Investitionen stellen: diskret, strukturiert, unabh\u00e4ngig und mit einem klaren Blick f\u00fcr nachhaltige Werte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-196c208600cd4421c7cc6f0a3afb1783\" style=\"color:#9a9a9a\">Unsere Arbeitsweise<\/h2>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-ac2ed3b2d0d020811837fe815a05dbed wp-block-paragraph\" style=\"color:#9a9a9a\">Jede Immobilie und jede Transaktion ist einzigartig. Deshalb setzen wir nicht auf standardisierte Vermarktung, sondern auf eine individuelle Strategie, die sich an den Zielen unserer Auftraggeber orientiert. Wir begleiten Eigent\u00fcmer, Unternehmerfamilien, Investoren und Projektentwickler von der ersten Analyse \u00fcber die Entwicklung einer Vermarktungs- oder Investmentstrategie bis hin zur strukturierten Ansprache geeigneter K\u00e4ufer oder Investoren und dem erfolgreichen Abschluss der Transaktion.<\/p>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-50737c71433f9806bb159b6025957762 wp-block-paragraph\" style=\"color:#9a9a9a\">Je nach Aufgabenstellung koordinieren wir dabei die Zusammenarbeit mit Notaren, Fachanw\u00e4lten, Steuerberatern, Architekten, Sachverst\u00e4ndigen, Finanzierungspartnern und weiteren Spezialisten. So entsteht f\u00fcr unsere Mandanten ein effizienter und professionell gesteuerter Transaktionsprozess aus einer Hand.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-aa509063ef0fe8694f229fab14752582\" style=\"color:#9a9a9a\">Ronald Wagschal<\/h2>\n\n\n\n<p class=\"has-text-color has-link-color has-small-font-size wp-elements-e18a1ca23aa07370b50ac89172c3b5d4 wp-block-paragraph\" style=\"color:#9a9a9a\">Ronald Wagschal ist Gr\u00fcnder und Inhaber von W&amp;P Estates. Mit einer fundierten Ausbildung , dem Besuch der Hotelfachschule sowie einem erfolgreich abgeschlossenen Studium der Betriebswirtschaft legte er den Grundstein f\u00fcr seine unternehmerische Laufbahn.<\/p>\n\n\n\n<p class=\"has-text-color has-link-color has-small-font-size wp-elements-8b3d49a7f42d68051ebaf710b5270e21 wp-block-paragraph\" style=\"color:#9a9a9a\">Seit mehr als 25 Jahren ist er als Unternehmer in den Bereichen Immobilien, Investments, Marketing und Unternehmensentwicklung t\u00e4tig. Berufliche Stationen in Berlin, London, Spanien, Japan und weiteren internationalen M\u00e4rkten pr\u00e4gten seinen Blick f\u00fcr unterschiedliche Investmentstrategien und grenz\u00fcberschreitende Transaktionen.<\/p>\n\n\n\n<p class=\"has-text-color has-link-color has-small-font-size wp-elements-da4053df4537f35f9351aa3434972702 wp-block-paragraph\" style=\"color:#9a9a9a\">Heute begleitet er Eigent\u00fcmer, Unternehmerfamilien, Investoren und Projektentwickler bei anspruchsvollen Immobilienmandaten und Off-Market-Transaktionen. Dabei verbindet er unternehmerisches Denken mit einem internationalen Netzwerk und einer diskreten, l\u00f6sungsorientierten Arbeitsweise.<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:33% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"1024\" src=\"https:\/\/wp-estates.com\/wp-content\/uploads\/2026\/06\/DSC_0754-1-740x1024.jpg\" alt=\"\" class=\"wp-image-309 size-full\" srcset=\"https:\/\/wp-estates.com\/wp-content\/uploads\/2026\/06\/DSC_0754-1-740x1024.jpg 740w, https:\/\/wp-estates.com\/wp-content\/uploads\/2026\/06\/DSC_0754-1-217x300.jpg 217w, https:\/\/wp-estates.com\/wp-content\/uploads\/2026\/06\/DSC_0754-1-768x1062.jpg 768w, https:\/\/wp-estates.com\/wp-content\/uploads\/2026\/06\/DSC_0754-1-1111x1536.jpg 1111w, https:\/\/wp-estates.com\/wp-content\/uploads\/2026\/06\/DSC_0754-1-1481x2048.jpg 1481w, https:\/\/wp-estates.com\/wp-content\/uploads\/2026\/06\/DSC_0754-1-scaled.jpg 1851w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-color has-link-color wp-elements-66f35ba363a70225be3a48a26ca1d6a1 wp-block-paragraph\" style=\"color:#c4a35a\">\u201e<strong><strong>Chancen erkennen. Menschen verbinden. Werte schaffen.<\/strong><\/strong>\u201c<\/p>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-508be759b4e8d0935983a514a95c304f wp-block-paragraph\" style=\"color:#9a9a9a\"><\/p>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-b91bc2487a528f22bfa908bd93697cac wp-block-paragraph\" style=\"color:#9a9a9a\"><\/p>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-b91bc2487a528f22bfa908bd93697cac wp-block-paragraph\" style=\"color:#9a9a9a\"><\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-38773cf4c8c631331df9ced73f38aeec\" style=\"color:#9a9a9a\">QUALIFIKATION &amp; ERFAHRUNG<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-text-color has-link-color wp-elements-0b373b0d8fb41cfb7eb0f34aa46c2607\" style=\"color:#9a9a9a\">\u00dcber 25 Jahre Unternehmererfahrung<\/li>\n\n\n\n<li class=\"has-text-color has-link-color wp-elements-2c861f22970d6833191459602b7302d6\" style=\"color:#9a9a9a\">Erfolgreich abgeschlossenes Studium der Betriebswirtschaft<\/li>\n\n\n\n<li class=\"has-text-color has-link-color wp-elements-00fa68f4ecfa2d610051ff3c0c9f212a\" style=\"color:#9a9a9a\">Unternehmensgr\u00fcndungen und Beteiligungen im In- und Ausland<\/li>\n\n\n\n<li class=\"has-text-color has-link-color wp-elements-a504575455757e88e558a6993e35b106\" style=\"color:#9a9a9a\">Internationale T\u00e4tigkeit in Europa und Asien<\/li>\n\n\n\n<li class=\"has-text-color has-link-color wp-elements-43f3c85bf676331cd56bc80318aec4ca\" style=\"color:#9a9a9a\">Erfahrung in den Bereichen Immobilien, Investments und Unternehmensentwicklung<\/li>\n\n\n\n<li class=\"has-text-color has-link-color wp-elements-8c0b412f9510cc57cb64546f48ac6796\" style=\"color:#9a9a9a\">Langj\u00e4hrige Zusammenarbeit mit Eigent\u00fcmern, Unternehmerfamilien, Investoren und Projektpartnern<\/li>\n\n\n\n<li class=\"has-text-color has-link-color wp-elements-3bc879a4a23d4bfd300cac59d44c4789\" style=\"color:#9a9a9a\">Renewable Energy &amp; Infrastrukturprojekte<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading96_417f60-4f, .wp-block-kadence-advancedheading.kt-adv-heading96_417f60-4f[data-kb-block=\"kb-adv-heading96_417f60-4f\"]{max-width:692px;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;color:#c4a35a;}.wp-block-kadence-advancedheading.kt-adv-heading96_417f60-4f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading96_417f60-4f[data-kb-block=\"kb-adv-heading96_417f60-4f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading96_417f60-4f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading96_417f60-4f[data-kb-block=\"kb-adv-heading96_417f60-4f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading96_417f60-4f wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading96_417f60-4f\">W&amp;P Estates ist Teil der W&amp;P Unternehmensgruppe mit Aktivit\u00e4ten in den Bereichen Immobilien, Investments, Projektentwicklung und erneuerbare Energien.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unternehmerisch. Diskret. Pers\u00f6nlich \u00dcber W&amp;P Estates Unternehmerische Erfahrung. Internationale Perspektive. Pers\u00f6nliche Beratung. W&amp;P Estates ist eine inhabergef\u00fchrte Boutique-Beratung f\u00fcr Off-Market-Immobilien, Investmenttransaktionen und strategische Immobilienberatung. Seit mehr als 25 Jahren begleiten wir Eigent\u00fcmer, Unternehmerfamilien, Investoren und Projektentwickler bei anspruchsvollen Immobilienvorhaben \u2013 diskret, pers\u00f6nlich und mit unternehmerischem Verst\u00e4ndnis. Unsere Philosophie Immobilien sind mehr als Verm\u00f6genswerte \u2013 sie&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-96","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/wp-estates.com\/en\/wp-json\/wp\/v2\/pages\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp-estates.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wp-estates.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wp-estates.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp-estates.com\/en\/wp-json\/wp\/v2\/comments?post=96"}],"version-history":[{"count":28,"href":"https:\/\/wp-estates.com\/en\/wp-json\/wp\/v2\/pages\/96\/revisions"}],"predecessor-version":[{"id":1210,"href":"https:\/\/wp-estates.com\/en\/wp-json\/wp\/v2\/pages\/96\/revisions\/1210"}],"wp:attachment":[{"href":"https:\/\/wp-estates.com\/en\/wp-json\/wp\/v2\/media?parent=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}